{"id":1512,"date":"2022-04-21T08:59:00","date_gmt":"2022-04-21T08:59:00","guid":{"rendered":"https:\/\/www.freenekane.ch\/?p=1512"},"modified":"2022-04-22T13:17:41","modified_gmt":"2022-04-22T13:17:41","slug":"castellano-nekane-hemos-parado-la-persecucion-politica","status":"publish","type":"post","link":"http:\/\/www.freenekane.ch\/fr\/castellano-nekane-hemos-parado-la-persecucion-politica\/","title":{"rendered":"(Castellano) Nekane: &#8220;\u00a1Hemos parado la persecuci\u00f3n pol\u00edtica!&#8221;"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.freenekane.ch\/wp-content\/uploads\/signal-2022-04-21-004128_001-1600x1600.jpeg\" alt=\"\" class=\"wp-image-1483\" width=\"225\" height=\"230\"\/><figcaption>En el monte Ernio, Asteasu, pidiendo que &#8220;l\u00d7s presxs y refugiadxs vascxs vuelvan a casa&#8221;<\/figcaption><\/figure><\/div>\n\n\n\n<p>Estoy en el Pa\u00eds Vasco con mi hija. La orden de detenci\u00f3n internacional y la solicitud de extradici\u00f3n contra m\u00ed fueron canceladas a principios de abril. Tras 15 a\u00f1os de hu\u00ecda, pude abrazar a mi madre enferma y a mis hermanxs, familiares y amigxs. Esto ha sido posible gracias a nuestra lucha colectiva! He sobrevivido a detenciones, secuestros, torturas sexistas, violaci\u00f2n, juicios pol\u00edticos, huidas, ilegalidad y prisi\u00f3n. He superado todo esto junto a vosotrxs, gracias a vuestro apoyo y solidaridad. <\/p>\n\n\n\n<p>Era hora de poner fin a la persecuci\u00f3n pol\u00edtica y a las dificultades administrativas que ten\u00edamos que soportar. A trav\u00e9s de todos los a\u00f1os de lucha conjunta, hemos creado las condiciones para una soluci\u00f3n jur\u00eddica. El Tribunal Especial, la Audiencia Nacional, ha retirado todos los cargos contra m\u00ed, excepto la posesi\u00f3n de dos documentos de identidad falsos. <\/p>\n\n\n\n<p>Por ello, ahora puedo moverme libremente. He pasado casi un tercio de mi vida huyendo en el exilio. La fuga es una ruptura, un billete de s\u00f2lo ida. Sab\u00eda que podr\u00eda durar mucho tiempo o que podr\u00eda no volver nunca. Pero siempre confi\u00e9 en el movimiento y en la solidaridad de la gente, y sab\u00eda que ese regreso depender\u00eda de la lucha que llev\u00e1ramos a cabo. Tambi\u00e9n encontr\u00e9 un lugar de lucha en el exilio y eso facilit\u00f2 el d\u00eda a d\u012ba. <\/p>\n\n\n\n<p>Ahora tenemos un \u00e9xito que celebrar. En mayo, volver\u00e9 a Z\u00farich para compartir con vosotrxs las hermosas experiencias de solidaridad, amor y lucha. Seguiremos luchando por nuestros objetivos, hasta que todxs  seamos libres<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estoy en el Pa\u00eds Vasco con mi hija. La orden de detenci\u00f3n internacional y la solicitud de extradici\u00f3n contra m\u00ed fueron canceladas a principios de abril. Tras 15 a\u00f1os de hu\u00ecda, pude abrazar a mi madre enferma y a mis &hellip; <a href=\"http:\/\/www.freenekane.ch\/fr\/castellano-nekane-hemos-parado-la-persecucion-politica\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[9,3],"tags":[],"_links":{"self":[{"href":"http:\/\/www.freenekane.ch\/fr\/wp-json\/wp\/v2\/posts\/1512"}],"collection":[{"href":"http:\/\/www.freenekane.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.freenekane.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.freenekane.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.freenekane.ch\/fr\/wp-json\/wp\/v2\/comments?post=1512"}],"version-history":[{"count":1,"href":"http:\/\/www.freenekane.ch\/fr\/wp-json\/wp\/v2\/posts\/1512\/revisions"}],"predecessor-version":[{"id":1514,"href":"http:\/\/www.freenekane.ch\/fr\/wp-json\/wp\/v2\/posts\/1512\/revisions\/1514"}],"wp:attachment":[{"href":"http:\/\/www.freenekane.ch\/fr\/wp-json\/wp\/v2\/media?parent=1512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.freenekane.ch\/fr\/wp-json\/wp\/v2\/categories?post=1512"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.freenekane.ch\/fr\/wp-json\/wp\/v2\/tags?post=1512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}